{"id":26499,"date":"2015-02-23T12:34:59","date_gmt":"2015-02-23T10:34:59","guid":{"rendered":"http:\/\/www.malerdeck.de\/blog\/?p=26499"},"modified":"2015-02-23T12:34:59","modified_gmt":"2015-02-23T10:34:59","slug":"im-februar-2015-auf-der-homepage-noch-ein-angebot-aus-dem-herbst-2012-und-das-unter-aktuell","status":"publish","type":"post","link":"https:\/\/www.malerdeck.de\/blog\/im-februar-2015-auf-der-homepage-noch-ein-angebot-aus-dem-herbst-2012-und-das-unter-aktuell","title":{"rendered":"Im Februar 2015: Auf der Homepage noch ein Angebot aus dem &#8222;Herbst 2012&#8220;. Und das unter &#8222;Aktuell&#8220;"},"content":{"rendered":"<p style=\"text-align: justify;\">Dieser Kollege scheint nicht ganz auf der H\u00f6he der Zeit. Offensichtlich hat er auch schon mehrere Jahre seine Internetseite nicht mehr angesehen. Zudem sind die winzigen Schriften in Logo und Wappen nicht zu lesen.<\/p>\n<div id=\"attachment_26500\" style=\"width: 563px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.malerdeck.de\/blog\/wp-content\/uploads\/2015\/02\/Veraltetes-Angebot.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26500\" class=\"wp-image-26500\" src=\"http:\/\/www.malerdeck.de\/blog\/wp-content\/uploads\/2015\/02\/Veraltetes-Angebot.jpg\" alt=\"Veraltetes Angebot\" width=\"553\" height=\"258\" srcset=\"https:\/\/www.malerdeck.de\/blog\/wp-content\/uploads\/2015\/02\/Veraltetes-Angebot.jpg 750w, https:\/\/www.malerdeck.de\/blog\/wp-content\/uploads\/2015\/02\/Veraltetes-Angebot-300x140.jpg 300w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-26500\" class=\"wp-caption-text\">Ist das noch &#8222;Aktuell&#8220;?<\/p><\/div>\n<p style=\"text-align: justify;\">Wie wirkt das wohl auf die Seitenbesucher? Und die Rabattregelung? Ab welchem Jahrzehnt beginnt ein &#8222;Senior&#8220;? \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieser Kollege scheint nicht ganz auf der H\u00f6he der Zeit. Offensichtlich hat er auch schon mehrere Jahre seine Internetseite nicht mehr angesehen. Zudem sind die winzigen Schriften in Logo und Wappen nicht zu lesen. Wie wirkt das wohl auf die Seitenbesucher? Und die Rabattregelung? Ab welchem Jahrzehnt beginnt ein &#8222;Senior&#8220;? \ud83d\ude09<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,37],"tags":[1159,1146,1161,2952],"class_list":["post-26499","post","type-post","status-publish","format-standard","hentry","category-kundeninformation","category-wettbewerber","tag-aktuell","tag-homepage","tag-veraltet","tag-wettbewerber"],"_links":{"self":[{"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/posts\/26499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/comments?post=26499"}],"version-history":[{"count":6,"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/posts\/26499\/revisions"}],"predecessor-version":[{"id":26506,"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/posts\/26499\/revisions\/26506"}],"wp:attachment":[{"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/media?parent=26499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/categories?post=26499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.malerdeck.de\/blog\/wp-json\/wp\/v2\/tags?post=26499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}